{"id":2315,"date":"2015-08-20T08:52:54","date_gmt":"2015-08-20T06:52:54","guid":{"rendered":"http:\/\/www.iberradio.es\/?p=2315"},"modified":"2016-05-31T19:38:30","modified_gmt":"2016-05-31T17:38:30","slug":"sesion-de-examenes-para-licencias-usa","status":"publish","type":"post","link":"https:\/\/www.iberradio.es\/en\/sesion-de-examenes-para-licencias-usa\/","title":{"rendered":"Sesi\u00f3n de ex\u00e1menes para licencias USA en IberRadio"},"content":{"rendered":"<p><?php\n\n$qrz = strtr(strtoupper($_POST[qrz]),\"\u00e0\u00e8\u00ec\u00f2\u00f9\u00e1\u00e9\u00ed\u00f3\u00fa\u00e7\u00f1\u00e4\u00eb\u00ef\u00f6\u00fc\",\"\u00c0\u00c8\u00cc\u00d2\u00d9\u00c1\u00c9\u00cd\u00d3\u00da\u00c7\u00d1\u00c4\u00cb\u00cf\u00d6\u00dc\");\n$nombre = strtr(strtoupper($_POST[nombre]),\"\u00e0\u00e8\u00ec\u00f2\u00f9\u00e1\u00e9\u00ed\u00f3\u00fa\u00e7\u00f1\u00e4\u00eb\u00ef\u00f6\u00fc\",\"\u00c0\u00c8\u00cc\u00d2\u00d9\u00c1\u00c9\u00cd\u00d3\u00da\u00c7\u00d1\u00c4\u00cb\u00cf\u00d6\u00dc\");\n$email = $_POST[email];\n$ip = $_SERVER['REMOTE_ADDR'];\n$date = date('Y-m-d H:i:s'); \n\n$qrz = trim($qrz, ' ');   \/\/ QUITA ESPACIO AL PRINCIPIO Y FINAL\n$nombre = trim($nombre, ' ');\n$email = trim($email, ' ');\n\n\n\nif ($nombre == \"\" &#038;&#038; $email == \"\" &#038;&#038; $_GET[c1] == '') {\n?><\/p>\n<h5 style=\"text-align: justify;\">Debido a la elevada demanda y para asignar adecuadamente las salas de examen solicitamos que los interesados en realizar los ex\u00e1menes para las licencias de radioaficionado de la FCC de los EEUU, se inscriban previamente. De esta manera se garantizar\u00e1n plaza en las sesiones de examen.<\/h5>\n<h5 style=\"text-align: justify;\">\u2013 Los ex\u00e1menes se realizar\u00e1n exclusivamente en idioma ingl\u00e9s. Sin embargo los Examinadores Certificados explicar\u00e1n las instrucciones para realizar el examen y resolver\u00e1n dudas de caracter previo al examen en espa\u00f1ol.<br \/>\n<\/h5>\n<h5 style=\"text-align: justify;\">&#8211; No se permite el uso de dispositivos electr\u00f3nicos, ni traductores ni diccionarios, as\u00ed como ning\u00fan otro tipo de material de apoyo (excepto calculadora no programable).<\/h5>\n<h5 style=\"text-align: justify;\">&#8211; Los ex\u00e1menes de las clases Technician y General constan de 35 preguntas de las que hay que responder correctamente a 26 para superarlos. El examen de la clase Extra consta de 50 preguntas de las que hay que responder correctamente al menos a 37 preguntas.<\/h5>\n<h5 style=\"text-align: justify;\">&#8211; La primera ronda de examen se iniciar\u00e1 el domingo a las 10.00 am en la Sala 1, planta 1 de la Casa de la Juventud de Parla.<\/h5>\n<h5 style=\"text-align: justify;\">&#8211; Los derechos de examen son 15 US$ o 14 \u20ac que se abonar\u00e1n previamente a la entrada en la sala de examen. Este importe da derecho a realizar los ex\u00e1menes de las tres clases de licencia de manera consecutiva. Superando un examen se puede realizar el de la clase inmediatamente superior en la misma sesi\u00f3n sin cargo adicional. Si se suspende un examen se puede intentar de nuevo en la misma sesi\u00f3n de examen abonando nuevamente los derechos de examen.<\/h5>\n<\/p>\n<p><\/p>\n<h5 style=\"text-align: justify;\">Recordamos que los candidatos a examen deber\u00e1n traer:<\/h5>\n<h5 style=\"text-align: justify;\">\u2013 DNI o pasaporte.<\/h5>\n<h5 style=\"text-align: justify;\">\u2013 Es IMPRESCINDIBLE una direcci\u00f3n postal en EEUU para hacer llegar correspondencia de la FCC. Esta direcci\u00f3n puede ser de un amigo, otro OM o un familiar. Se aceptan apartados postales. La FCC asigna el indicativo de EEUU en funci\u00f3n del distrito de la direcci\u00f3n aportada.<\/h5>\n<h5 style=\"text-align: justify;\">\u2013 Si ya se dispone de una licencia USA, se deber\u00e1 aportar el original de la licencia FCC o copia validada.<\/h5>\n<h5 style=\"text-align: justify;\">\u2013 L\u00e1piz, goma de borrar, bol\u00edgrafo y calculadora no programable.<\/h5>\n<h5 style=\"text-align: justify;\">&#8211; Los ciudadanos de los EEUU deber\u00e1n aportar su n\u00famero de la Seguridad Social \u00f3 TIN, que ser\u00e1 incorporado en el impreso 605.<\/h5>\n<h5 style=\"text-align: justify;\">&#8211; Para cualquier cuesti\u00f3n o aclaraci\u00f3n pueden dirigirse a Salvador Dom\u00e9nech EA5DY\/KH8E, VEC Session Liaison en ea5dy @ ure.es<\/h5>\n<\/p>\n<hr>\n<\/hr>\n<p><center><span><font size=\"4\"><b>FORMULARIO DE PREINSCRIPCI\u00d3N PARA LA<br \/>SESI\u00d3N DE EX\u00c1MENES LICENCIAS USA<\/b><\/font><\/span><\/center><\/p>\n<h5 style=\"text-align: justify;\">Debido a limitaciones en el aforo de las salas de examen en IberRadio el n\u00famero m\u00e1ximo de candidatos se ha establecido en 80.<\/h5>\n<h5 style=\"text-align: justify;\">Pr\u00f3ximamente se anunciar\u00e1n nuevas convocatorias de examen en otras fechas.<\/h5>\n<p><?php\n\n$query2 = \"SELECT COUNT(id) FROM examenes\";\n$result2 = mysql_query($query2) or die(mysql_error());\n$row = mysql_fetch_row($result2);\n$total = $row[0];\n\necho \"<\/p>\n<hr>\n<\/hr>\n<h1><strong>PREINSCRITOS<\/strong> ($total)<\/h1>\n<hr\/>\n<p>&#8220;;<\/p>\n<p>?><\/p>\n<style>\n.celda0{width:120px; height:40px; float:left;}\n.celda1{height:160px; float:left;}\n<\/style>\n<p><?php\n\n\/\/$query = \"SELECT qrz FROM examenes where qrz NOT REGEXP 'NO 2015' order by qrz ASC\";\n\n$query = \"SELECT qrz FROM examenes where qrz LIKE 'EA1%' OR qrz LIKE 'EA2%' OR qrz LIKE 'EA3%' OR qrz LIKE 'EA4%' OR qrz LIKE 'EA5%' OR qrz LIKE 'EA6%' OR qrz LIKE 'EA7%' OR qrz LIKE 'EA8%' OR qrz LIKE 'EA9%' OR qrz LIKE 'EB1%' OR qrz LIKE 'EB2%' OR qrz LIKE 'EB3%' OR qrz LIKE 'EB4%' OR qrz LIKE 'EB5%' OR qrz LIKE 'EB6%' OR qrz LIKE 'EB7%' OR qrz LIKE 'EB8%' OR qrz LIKE 'EB9%' OR qrz LIKE 'EC1%' OR qrz LIKE 'EC2%' OR qrz LIKE 'EC3%' OR qrz LIKE 'EC4%' OR qrz LIKE 'EC5%' OR qrz LIKE 'EC6%' OR qrz LIKE 'EC7%' OR qrz LIKE 'EC8%' OR qrz LIKE 'EC9%' OR qrz = 'KD7JWK'  OR qrz = 'KG5CXO'  OR qrz = 'KJ6JLM' OR qrz = 'ECB85OVF' order by qrz ASC\";\n$result = mysql_query($query) or die(mysql_error());\nwhile($row = mysql_fetch_array($result)){\n\necho \"\n\n<div class=celda0>\n<h5><strong>$row[qrz]<\/strong><\/h5>\n<\/div>\n<p>&#8220;;<br \/>\n}<\/p>\n<p>\/\/echo &#8220;<\/p>\n<div class=celda1><\/div>\n<p>&#8220;;<\/p>\n<p>$query6 = &#8220;SELECT id FROM examenes where qrz REGEXP &#8216;NO 2015&#8242;&#8221;;<br \/>\n$result6 = mysql_query($query6) or die();<br \/>\n$num_rows6 = mysql_num_rows($result6);<br \/>\nif ($num_rows6 >= &#8216;1&#8217;) {<br \/>\necho &#8220;<\/p>\n<h5><strong><i>* Sin indicativo ($num_rows6)<\/i><\/strong><\/h5>\n<p>&#8220;;<br \/>\n}<br \/>\n}<br \/>\n\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/<br \/>\n$paso = $_GET[c1];<\/p>\n<p>?><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a la elevada demanda y para asignar adecuadamente las salas de examen solicitamos que los interesados en realizar los ex\u00e1menes para las licencias de radioaficionado de la FCC de los EEUU, se inscriban previamente. De esta manera se garantizar\u00e1n plaza en las sesiones de examen. \u2013 Los ex\u00e1menes se realizar\u00e1n exclusivamente en idioma ingl\u00e9s. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-2315","post","type-post","status-publish","format-standard","hentry","category-noticias-2015"],"_links":{"self":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts\/2315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/comments?post=2315"}],"version-history":[{"count":14,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts\/2315\/revisions"}],"predecessor-version":[{"id":2596,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts\/2315\/revisions\/2596"}],"wp:attachment":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/media?parent=2315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/categories?post=2315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/tags?post=2315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}