{"id":4477,"date":"2016-09-14T12:01:32","date_gmt":"2016-09-14T10:01:32","guid":{"rendered":"http:\/\/www.iberradio.es\/?p=4477"},"modified":"2018-06-17T20:09:05","modified_gmt":"2018-06-17T18:09:05","slug":"simulacro-de-llamada-de-socorro","status":"publish","type":"post","link":"https:\/\/www.iberradio.es\/en\/simulacro-de-llamada-de-socorro\/","title":{"rendered":"Simulacro de llamada de socorro"},"content":{"rendered":"<p><\/p>\n<h5 align=\"justify\">Durante la celebraci\u00f3n de la feria IBERRADIO, realizaremos la actividad SIMULACRO DE LLAMADA DE SOCORRO POR SINIESTRO TOTAL con la estaci\u00f3n EG4IBS.<\/h5>\n<h5 align=\"justify\">La estaci\u00f3n estar\u00e1 compuesta por dos equipos multibanda a 12v.<\/h5>\n<h5 align=\"justify\">Las antenas ser\u00e1n las construidas por nosotros con los materiales seleccionados a tal fin de entre los restos del siniestro (cables rescatados del suelo,  cuerdas,  maderas,  etc.).<\/h5>\n<h5 align=\"justify\">La alimentaci\u00f3n de los equipos ser\u00e1n, bater\u00edas que se rescaten de los veh\u00edculos siniestrados.<\/h5>\n<h5 align=\"justify\">La actividad se realizara en la explanada de la entrada principal de Lienzo Norte. Saldremos al aire en todas las bandas de HF, VHF y UHF en fon\u00eda (bandas laterales) FM y telegraf\u00eda.<\/h5>\n<h5 align=\"justify\">A las estaciones que contacten una sola vez con nosotros en cualquier banda y modo se le otorgar\u00e1 un diploma de la actividad que podr\u00e1n descargarse de la p\u00e1gina que comunicaremos cuando sepamos exactamente cu\u00e1l va a ser.<\/h5>\n<h5 align=\"justify\">Estaremos operando la estaci\u00f3n durante el tiempo que permanezca abierto el IBERRADIO tanto el s\u00e1bado como el domingo, no obstante no ser\u00e1 de manera continuada porque nos ausentaremos para hacer otras actividades en la feria y para dejar operar a la estaci\u00f3n oficial de la misma. Las horas de la actividad ser\u00e1n como m\u00ednimo a las 11:00, 13:00 y 16:30 del s\u00e1bado d\u00eda 17 de septiembre.<\/h5>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Durante la celebraci\u00f3n de la feria IBERRADIO, realizaremos la actividad SIMULACRO DE LLAMADA DE SOCORRO POR SINIESTRO TOTAL con la estaci\u00f3n EG4IBS. La estaci\u00f3n estar\u00e1 compuesta por dos equipos multibanda a 12v. Las antenas ser\u00e1n las construidas por nosotros con los materiales seleccionados a tal fin de entre los restos del siniestro (cables rescatados del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-4477","post","type-post","status-publish","format-standard","hentry","category-noticias-2016"],"_links":{"self":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts\/4477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/comments?post=4477"}],"version-history":[{"count":2,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts\/4477\/revisions"}],"predecessor-version":[{"id":4480,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/posts\/4477\/revisions\/4480"}],"wp:attachment":[{"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/media?parent=4477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/categories?post=4477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iberradio.es\/en\/wp-json\/wp\/v2\/tags?post=4477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}