{"id":3835,"date":"2016-08-02T18:15:13","date_gmt":"2016-08-02T16:15:13","guid":{"rendered":"http:\/\/www.iberradio.es\/?p=3835"},"modified":"2017-05-09T14:20:05","modified_gmt":"2017-05-09T12:20:05","slug":"viaje-de-ciudad-real-a-avila","status":"publish","type":"post","link":"https:\/\/www.iberradio.es\/pt\/viaje-de-ciudad-real-a-avila\/","title":{"rendered":"Viagem de Ciudad Real para Avila"},"content":{"rendered":"<p style=\"text-align: justify;\">Uni\u00f3n de Radioaficionados de Ciudad Real (URCR) organiza un viaje en autob\u00fas a \u00c1vila el pr\u00f3ximo 17 de septiembre con motivo de IberRadio.<\/p>\n<p><strong>El programa seria:<\/strong><\/p>\n<p>&#8211; Salida de Ciudad Real 7.00 horas. Plaza San Francisco.<\/p>\n<p>&#8211; Comida, 14,30 en restaurante el Lienzo, junto al Centro de Congresos y Exposiciones<\/p>\n<p>&#8211; Salida de \u00c1vila a las 20 horas.<\/p>\n<p>Regreso estimado en la capital de Ciudad Real 23,00 horas<\/p>\n<p>Se pueden apuntar familiares y amigos hacer turismo por la ciudad, si les apetece. Mientras los interesados estamos en el importante evento.<\/p>\n<p>El precio puede variar seg\u00fan el numero de interesados en este viaje.<br \/>\nEstimaci\u00f3n aproximada viaje en autob\u00fas ida y vuelta con comida. 55 \/ 60 \u20ac por persona.<\/p>\n<p>Con el fin de hacer previsiones y reservas, los interesados pueden comunicarlo a <strong><a href=\"mailto:Ea4pc@ure.es\">Ea4pc@ure.es<\/a><\/strong> o al tel\u00e9fono 609172594 con Whatsapp.<\/p>\n<p>Saludos cordiales.<br \/>\n<strong>Uni\u00f3n de Radioaficionados de Ciudad Real (URCR)<\/strong><br \/>\n<strong><a href=\"http:\/\/www.urcr.es\" target=\"_blank\">www.urcr.es<\/a><\/strong><br \/>\nApartado de coreos, 13 &#8211; 113080 Ciudad Real<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uni\u00f3n de Radioaficionados de Ciudad Real (URCR) organiza un viaje en autob\u00fas a \u00c1vila el pr\u00f3ximo 17 de septiembre con motivo de IberRadio. El programa seria: &#8211; Salida de Ciudad Real 7.00 horas. Plaza San Francisco. &#8211; Comida, 14,30 en restaurante el Lienzo, junto al Centro de Congresos y Exposiciones &#8211; Salida de \u00c1vila a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-3835","post","type-post","status-publish","format-standard","hentry","category-noticias-2016"],"_links":{"self":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts\/3835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/comments?post=3835"}],"version-history":[{"count":4,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts\/3835\/revisions"}],"predecessor-version":[{"id":4038,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts\/3835\/revisions\/4038"}],"wp:attachment":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/media?parent=3835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/categories?post=3835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/tags?post=3835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}