{"id":4249,"date":"2016-08-29T13:58:22","date_gmt":"2016-08-29T11:58:22","guid":{"rendered":"http:\/\/www.iberradio.es\/?p=4249"},"modified":"2019-07-08T16:17:40","modified_gmt":"2019-07-08T14:17:40","slug":"el-archivo-historico-ea4do-de-nuevo-en-iberradio","status":"publish","type":"post","link":"https:\/\/www.iberradio.es\/pt\/el-archivo-historico-ea4do-de-nuevo-en-iberradio\/","title":{"rendered":"El Archivo Hist\u00f3rico EA4DO de nuevo en IberRadio-2016"},"content":{"rendered":"<p><\/p>\n<h5 align=\"justify\">El <b>ARCHIVO HIST\u00d3RICO EA4DO<\/b> participar\u00e1 esta ocasi\u00f3n desde el stand del \u201cConsejo Territorial de URE \u2013 Madrid\u201d llevando a IberRadio el recuerdo de un importante evento que, desde el mes de octubre de 1926, trat\u00f3 de establecer las primeras comunicaciones radiotelegr\u00e1ficas en onda corta con los pa\u00edses hispano hablantes, no solo del continente americano sino tambi\u00e9n con Filipinas.<\/h5>\n<h5 align=\"justify\">La iniciativa entonces del Presidente-Fundador de la \u201cAsociaci\u00f3n EAR\u201d para convocar el <b>Concurso de Transmisi\u00f3n 1926-1927<\/b> fue consecuencia de las pruebas que, a partir de diciembre de 1921, hab\u00eda venido celebrando a\u00f1o tras a\u00f1o la A.R.R.L con la finalidad de establecer las primeras comunicaciones entre el nuevo y viejo continente durante el que se conoci\u00f3 inicialmente como \u201cTransatlantic Test\u201d, y pronto se convirti\u00f3 en el cl\u00e1sico concurso anual de la liga americana en el que desde entonces participan muchos aficionados al DX de todo el mundo.<\/h5>\n<p><strong><a href=\"http:\/\/www.facebook.com\/archivohistoricoea4do\/\" target=\"_blank\" rel=\"noopener noreferrer\"><\/p>\n<h5>www.facebook.com\/archivohistoricoea4do\/<\/h5>\n<p><\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El ARCHIVO HIST\u00d3RICO EA4DO participar\u00e1 esta ocasi\u00f3n desde el stand del \u201cConsejo Territorial de URE \u2013 Madrid\u201d llevando a IberRadio el recuerdo de un importante evento que, desde el mes de octubre de 1926, trat\u00f3 de establecer las primeras comunicaciones radiotelegr\u00e1ficas en onda corta con los pa\u00edses hispano hablantes, no solo del continente americano sino [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-4249","post","type-post","status-publish","format-standard","hentry","category-noticias-2016"],"_links":{"self":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts\/4249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/comments?post=4249"}],"version-history":[{"count":5,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts\/4249\/revisions"}],"predecessor-version":[{"id":9287,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/posts\/4249\/revisions\/9287"}],"wp:attachment":[{"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/media?parent=4249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/categories?post=4249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iberradio.es\/pt\/wp-json\/wp\/v2\/tags?post=4249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}